{"id":19665,"date":"2023-07-18T13:30:14","date_gmt":"2023-07-18T11:30:14","guid":{"rendered":"https:\/\/www.recharge.com\/blog?p=19665"},"modified":"2023-07-18T13:34:35","modified_gmt":"2023-07-18T11:34:35","slug":"sim-karte-verloren","status":"publish","type":"post","link":"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren","title":{"rendered":"SIM-Karte verloren? Das kannst du jetzt tun"},"content":{"rendered":"<p>Klein aber oho: Eine Nano-SIM misst gerade mal 8,8 x 12,3 mm und ist damit ungef\u00e4hr so gro\u00df wie ein Daumennagel. Trotzdem geht ohne sie Nix: Sie ist das Herzst\u00fcck jedes Mobiltelefons und enth\u00e4lt all unsere Kontakte. Doch was passiert, wenn du deine SIM-Karte verloren hast oder sogar dein Handy? Das ist nicht nur sehr \u00e4rgerlich, sondern birgt auch die Gefahr, dass deine SIM und deine Daten in falsche H\u00e4nde geraten. In diesem Artikel erf\u00e4hrst du, was du beim Verlust deiner SIM-Karte unternehmen solltest und worauf du besonders achten musst.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>SIM-Karte verloren \u2013 Was jetzt?<\/strong><\/h2>\n<p>Erst mal Ruhe bewahren! Wichtig ist vor allem, dass du planvoll vorgehst. Folgende Schritte solltest du jetzt unternehmen:<\/p>\n<ul>\n<li>Rufe so schnell wie m\u00f6glich deinen Mobilfunkanbieter an, um den Verlust deiner SIM-Karte zu melden. Daf\u00fcr musst du dir unter Umst\u00e4nden das Handy eines Freundes ausleihen oder du versuchst, den Support deines Anbieters per Online-Chat zu erreichen. Vielleicht gibt es auch eine Filiale deines Anbieters in der N\u00e4he, dann kannst du direkt vorbeigehen.<\/li>\n<li>Und jetzt das Wichtigste: <strong>Bitte deinen Anbieter, die Nummer zu sperren, damit deine SIM-Karte nicht missbraucht wird!<\/strong> Dabei wirst du meistens nach deiner Rufnummer, der Nummer der SIM-Karte sowie deiner Kundennummer gefragt. Diese Infos solltest du also parat haben. Bei vielen Anbietern kannst du das sogar selbst tun. Daf\u00fcr musst du dich auf der Website des Providers einloggen.<\/li>\n<li>Dein Anbieter wird dir eine Ersatzkarte ausstellen. Per Post dauert das in der Regel einige Tage. In der Filiale geht es deutlich schneller. Wichtig ist, dass du dich ausweisen kannst, damit die Mitarbeiter deine Identit\u00e4t pr\u00fcfen k\u00f6nnen. Die Kosten f\u00fcr eine Ersatzkarte sind je nach Anbieter unterschiedlich.<\/li>\n<li>Wenn du dein Handy verloren hast, kannst du versuchen, es zu lokalisieren bzw. aus der Ferne zu sperren. Manche Handyhersteller bzw. Anbieter liefern Apps mit, die diese und weitere Funktionen erm\u00f6glichen (z. B. Fotos vom Dieb, der Displaysperre aufheben will).Wenn dein Handy gestohlen wurde, solltest du den Diebstahl auch bei der Polizei melden. Hilfreich ist dabei die <strong>IMEI-Nummer <\/strong>(<strong>I<\/strong>nternational\u00a0<strong>M<\/strong>obile\u00a0<strong>S<\/strong>tation\u00a0<strong>E<\/strong>quipment<strong>\u00a0I<\/strong>dentity), eine 15-stellige Seriennummer, mit der jedes Mobiltelefon identifiziert werden kann.\u00a0Wenn du dir diese nicht vorher notiert hast, findest du sie eventuell auf der Verpackung oder im Mobilfunkvertrag. Im Fall eines Diebstahls solltest du sicherheitshalber auch auf dem Handy gespeicherte Passw\u00f6rter \u00e4ndern.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><strong>SIM-Karte sperren \u2013 So geht\u2019s<\/strong><\/h2>\n<p>Wir haben f\u00fcr dich recherchiert, wie du deine SIM-Karte bei den drei gr\u00f6\u00dften Mobilfunkanbietern in \u00d6sterreich sperren lassen kannst.<\/p>\n<ul>\n<li>\n<h3><a href=\"https:\/\/www.recharge.com\/de\/at\/bfree\" target=\"_blank\" rel=\"noopener\">A1<\/a><\/h3>\n<\/li>\n<\/ul>\n<p>Du kannst deine SIM-Karte selbst sperren, indem du dich bei A1 einloggst und im Bereich Mein A1 auf \u201eJetzt Rufnummer sperren\u201c klickst. Um zu best\u00e4tigen, musst du dein Kundenkennwort eingeben. Falls du dein Kundenkennwort vergessen hast oder weitere Unterst\u00fctzung ben\u00f6tigst, kannst du dich direkt an den <a href=\"https:\/\/www.a1.net\/hilfe-kontakt\/article\/Vertrag-Services\/Mein-A1\/SIM-Karte-verwalten\/Wie-kann-ich-meine-Rufnummer-SIM-Karte-sperren-\/500000000007314\/500000000027914\" target=\"_blank\" rel=\"noopener\">Kundenservice von A1<\/a> wenden.<\/p>\n<ul>\n<li>\n<h3><a href=\"https:\/\/www.recharge.com\/de\/at\/drei\" target=\"_blank\" rel=\"noopener\">Drei<\/a><\/h3>\n<\/li>\n<\/ul>\n<p>Auch bei Drei kannst du deine SIM-Karte in der Kundenzone selbst sperren. Alternativ kannst du die Service-Hotline unter 0660\/303030 anrufen. Mit der <a href=\"https:\/\/www.drei.at\/de\/planet-drei\/blog\/artikel\/handy-gestohlen.html#:~:text=Unmittelbar%20nachdem%20Sie%20bemerken%2C%20dass,303030%20oder%20%C3%BCber%20die%20Kundenzone.\" target=\"_blank\" rel=\"noopener\">Drei Cloud und der Handyversicherung von Drei<\/a> kannst du dich schon vor dem Schadensfall absichern.<\/p>\n<ul>\n<li>\n<h3><a href=\"https:\/\/www.recharge.com\/de\/at\/magenta\" target=\"_blank\" rel=\"noopener\">Magenta<\/a><\/h3>\n<\/li>\n<\/ul>\n<p>Bei Magenta kannst du auch entweder die <a href=\"https:\/\/www.magenta.at\/hilfe-service\/service\" target=\"_blank\" rel=\"noopener\">Hotline von T-Mobile bzw. tele.ring<\/a> anrufen oder die Karten unter www.t-mobile.at oder www.telering.at selbst sperren. Auch Magenta hat spezielle Angebote, mit denen du die Daten auf deinem Handy sch\u00fctzen kannst, bevor es zum Verlust oder Diebstahl kommt.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>So sch\u00fctzt du deine Daten<\/strong><\/h2>\n<p>Wenn das Handy erstmal gestohlen wurde oder die SIM-Karte verloren ist, ist es eigentlich schon zu sp\u00e4t. Idealerweise besch\u00e4ftigst du dich schon vorher mit dem Thema Datenschutz und triffst entsprechende Vorkehrungen. Auf Apple-Ger\u00e4ten und vielen Android-Ger\u00e4ten kannst du z.\u00a0B. die Standortverfolgung aktivieren. So kannst du sehen, wo sich dein Handy befindet. Au\u00dferdem gibt es eine ganze Reihe von Apps, mit denen du deine Daten in der Cloud sichern und\/oder verschl\u00fcsseln kannst. Auch eine Handyversicherung solltest du in Betracht ziehen, wenn du ein besonders teures Handy besitzt oder es h\u00e4ufig verlierst.<\/p>\n<p>&nbsp;<\/p>\n<h3>Related Products<\/h3>\r\n<div class=\"mobile-flex aroowproducts hide-tablet\">\r\n    <div type=\"button\" onclick=\"slide('left')\" >\r\n        <span class=\"carousel-control-prev-icon\"><\/span>\r\n    <\/div>\r\n    <div type=\"button\" onclick=\"slide('right')\">\r\n        <span class=\"carousel-control-next-icon\"><\/span>\r\n    <\/div>\r\n<\/div>\r\n<div id=\"featuredP\" class=\"feature-products row\">\r\n            <div class=\"feature-product-container col-lg-3\" >\r\n                        <a id=\"fpl1\" onclick=\"intcount()\" rel=\"noopener\" class=\"button\" href=\"https:\/\/www.recharge.com\/de\/at\/bfree\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/creativegroup-blog-prd-eu-west-1-recharge-blog.s3.eu-west-1.amazonaws.com\/blog\/wp-content\/uploads\/2023\/07\/18130309\/A1_Bfree_Guthaben_aufladen_RE.png\" alt=\"A1 Bfree Guthaben aufladen\" \/>\r\n                                A1            <\/a>\r\n        <\/div>\r\n            <div class=\"feature-product-container col-lg-3\" >\r\n                        <a id=\"fpl1\" onclick=\"intcount()\" rel=\"noopener\" class=\"button\" href=\"https:\/\/www.recharge.com\/de\/at\/drei\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/creativegroup-blog-prd-eu-west-1-recharge-blog.s3.eu-west-1.amazonaws.com\/blog\/wp-content\/uploads\/2022\/12\/20104652\/Drei_product_card_label-1.jpg\" alt=\"drei aufladen\" \/>\r\n                                Drei            <\/a>\r\n        <\/div>\r\n            <div class=\"feature-product-container col-lg-3\" >\r\n                        <a id=\"fpl1\" onclick=\"intcount()\" rel=\"noopener\" class=\"button\" href=\"https:\/\/www.recharge.com\/de\/at\/magenta\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/creativegroup-blog-prd-eu-west-1-recharge-blog.s3.eu-west-1.amazonaws.com\/blog\/wp-content\/uploads\/2023\/07\/18130307\/magenta_aufladen_RE.png\" alt=\"Magenta aufladen\" \/>\r\n                                Magenta            <\/a>\r\n        <\/div>\r\n    <\/div>\r\n\n","protected":false},"excerpt":{"rendered":"<p>SIM-Karte verloren? Keine Panik! In unserem Artikel erf\u00e4hrst du, was du jetzt tun kannst und worauf du achten solltest.<\/p>\n","protected":false},"author":19,"featured_media":20055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"cos_headline_score":0,"cos_seo_score":0,"cos_headline_text":"SIM-Karte verloren? Das kannst du jetzt tun","cos_headline_has_been_analyzed":false,"cos_last_analyzed_headline":[],"_hreflang_tags":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[110],"tags":[349,325],"class_list":["post-19665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-verbindung-bleiben","tag-action-de","tag-awareness-de"],"jetpack_publicize_connections":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.4 (Yoast SEO v21.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SIM-Karte verloren? Das kannst du jetzt tun<\/title>\n<meta name=\"description\" content=\"SIM-Karte verloren? Keine Panik! In unserem Artikel erf\u00e4hrst du, was du jetzt tun kannst und worauf du achten solltest.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SIM-Karte verloren? Das kannst du jetzt tun\" \/>\n<meta property=\"og:description\" content=\"SIM-Karte verloren? Keine Panik! In unserem Artikel erf\u00e4hrst du, was du jetzt tun kannst und worauf du achten solltest.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren\" \/>\n<meta property=\"og:site_name\" content=\"Recharge Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-18T11:30:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-18T11:34:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/creativegroup-blog-prd-eu-west-1-recharge-blog.s3.eu-west-1.amazonaws.com\/blog\/wp-content\/uploads\/2023\/07\/18130532\/sim_karte_verloren_RE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jessika Reh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren\",\"url\":\"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren\",\"name\":\"SIM-Karte verloren? Das kannst du jetzt tun\",\"isPartOf\":{\"@id\":\"https:\/\/www.recharge.com\/blog\/de\/#website\"},\"datePublished\":\"2023-07-18T11:30:14+00:00\",\"dateModified\":\"2023-07-18T11:34:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.recharge.com\/blog\/de\/#\/schema\/person\/33247f09d0c09f2f1e6673f363c39b75\"},\"description\":\"SIM-Karte verloren? Keine Panik! In unserem Artikel erf\u00e4hrst du, was du jetzt tun kannst und worauf du achten solltest.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren#breadcrumb\"},\"inLanguage\":\"de-AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.recharge.com\/blog\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SIM-Karte verloren? Das kannst du jetzt tun\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.recharge.com\/blog\/de\/#website\",\"url\":\"https:\/\/www.recharge.com\/blog\/de\/\",\"name\":\"Recharge Blog\",\"description\":\"Everything about online safety, smart spending &amp; your digital lifestyle.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.recharge.com\/blog\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-AT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.recharge.com\/blog\/de\/#\/schema\/person\/33247f09d0c09f2f1e6673f363c39b75\",\"name\":\"Jessika Reh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\/\/www.recharge.com\/blog\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4cc4fe95f997b3aa54d5a696e5689c811e4ba56c0b1d0b0673164503c0cd86df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4cc4fe95f997b3aa54d5a696e5689c811e4ba56c0b1d0b0673164503c0cd86df?s=96&d=mm&r=g\",\"caption\":\"Jessika Reh\"},\"url\":\"https:\/\/www.recharge.com\/blog\/de\/author\/magali-karee\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SIM-Karte verloren? Das kannst du jetzt tun","description":"SIM-Karte verloren? Keine Panik! In unserem Artikel erf\u00e4hrst du, was du jetzt tun kannst und worauf du achten solltest.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren","og_locale":"de_DE","og_type":"article","og_title":"SIM-Karte verloren? Das kannst du jetzt tun","og_description":"SIM-Karte verloren? Keine Panik! In unserem Artikel erf\u00e4hrst du, was du jetzt tun kannst und worauf du achten solltest.","og_url":"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren","og_site_name":"Recharge Blog","article_published_time":"2023-07-18T11:30:14+00:00","article_modified_time":"2023-07-18T11:34:35+00:00","og_image":[{"width":2048,"height":1363,"url":"https:\/\/creativegroup-blog-prd-eu-west-1-recharge-blog.s3.eu-west-1.amazonaws.com\/blog\/wp-content\/uploads\/2023\/07\/18130532\/sim_karte_verloren_RE.jpg","type":"image\/jpeg"}],"author":"Jessika Reh","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren","url":"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren","name":"SIM-Karte verloren? Das kannst du jetzt tun","isPartOf":{"@id":"https:\/\/www.recharge.com\/blog\/de\/#website"},"datePublished":"2023-07-18T11:30:14+00:00","dateModified":"2023-07-18T11:34:35+00:00","author":{"@id":"https:\/\/www.recharge.com\/blog\/de\/#\/schema\/person\/33247f09d0c09f2f1e6673f363c39b75"},"description":"SIM-Karte verloren? Keine Panik! In unserem Artikel erf\u00e4hrst du, was du jetzt tun kannst und worauf du achten solltest.","breadcrumb":{"@id":"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren#breadcrumb"},"inLanguage":"de-AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.recharge.com\/blog\/de\/at\/sim-karte-verloren#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.recharge.com\/blog\/de"},{"@type":"ListItem","position":2,"name":"SIM-Karte verloren? Das kannst du jetzt tun"}]},{"@type":"WebSite","@id":"https:\/\/www.recharge.com\/blog\/de\/#website","url":"https:\/\/www.recharge.com\/blog\/de\/","name":"Recharge Blog","description":"Everything about online safety, smart spending &amp; your digital lifestyle.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.recharge.com\/blog\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-AT"},{"@type":"Person","@id":"https:\/\/www.recharge.com\/blog\/de\/#\/schema\/person\/33247f09d0c09f2f1e6673f363c39b75","name":"Jessika Reh","image":{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/www.recharge.com\/blog\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4cc4fe95f997b3aa54d5a696e5689c811e4ba56c0b1d0b0673164503c0cd86df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4cc4fe95f997b3aa54d5a696e5689c811e4ba56c0b1d0b0673164503c0cd86df?s=96&d=mm&r=g","caption":"Jessika Reh"},"url":"https:\/\/www.recharge.com\/blog\/de\/author\/magali-karee"}]}},"jetpack_featured_media_url":"https:\/\/creativegroup-blog-prd-eu-west-1-recharge-blog.s3.eu-west-1.amazonaws.com\/blog\/wp-content\/uploads\/2023\/07\/18130532\/sim_karte_verloren_RE.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.recharge.com\/blog\/de\/wp-json\/wp\/v2\/posts\/19665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.recharge.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.recharge.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.recharge.com\/blog\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.recharge.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=19665"}],"version-history":[{"count":4,"href":"https:\/\/www.recharge.com\/blog\/de\/wp-json\/wp\/v2\/posts\/19665\/revisions"}],"predecessor-version":[{"id":20034,"href":"https:\/\/www.recharge.com\/blog\/de\/wp-json\/wp\/v2\/posts\/19665\/revisions\/20034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.recharge.com\/blog\/de\/wp-json\/wp\/v2\/media\/20055"}],"wp:attachment":[{"href":"https:\/\/www.recharge.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=19665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.recharge.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=19665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.recharge.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=19665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}